{"id":1561,"date":"2019-05-16T14:38:52","date_gmt":"2019-05-16T12:38:52","guid":{"rendered":"https:\/\/learnattack.de\/magazin\/?p=1561"},"modified":"2019-08-29T15:01:19","modified_gmt":"2019-08-29T13:01:19","slug":"nichtversetzung-pro-kontra","status":"publish","type":"post","link":"https:\/\/learnattack.de\/magazin\/nichtversetzung-pro-kontra\/","title":{"rendered":"Nichtversetzung \u2013 Katastrophe oder neue Chance?"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column width=&#8221;1\/2&#8243;][vc_column_text]Die Ausgabe der Zeugnisse kann bei den einen Freude, bei anderen aber auch Sorgen und \u00c4ngste ausl\u00f6sen. N\u00e4mlich dann, wenn die schlechten Noten die Versetzung gef\u00e4hrden. Wie Sie auf dieses erste Warnsignal reagieren k\u00f6nnen, haben wir Ihnen bereits <a href=\"https:\/\/learnattack.de\/magazin\/kind-ist-versetzungsgefaehrdet\/\">hier<\/a> ans Herz gelegt. Aber was tun, wenn dann tats\u00e4chlich der \u201eblaue Brief\u201c ins Haus flattert oder Ihr Kind sitzen bleiben muss? Oder sollte bei einem unbefriedigenden Zeugnis sogar freiwillig wiederholt werden? Sogar Albert Einstein oder Harald Schmidt haben in ihrer Schulzeit eine Klasse wiederholt. Sitzen bleiben ist also kein Beinbruch \u2013 oder doch? Wir beleuchten in diesem Artikel die Vor- und Nachteile der Nichtversetzung.[\/vc_column_text][vc_column_text]<\/p>\n<h2>Inhalt<\/h2>\n<ul>\n<li><a href=\"#regelungen\">Regelungen bei Nichtversetzung<\/a><\/li>\n<li><a href=\"#abschaffung\">Die Abschaffung der Nichtversetzung<\/a><\/li>\n<li><a href=\"#chance\">Sitzenbleiben als Chance<\/a><\/li>\n<li><a href=\"#entscheidung\">Schwere Entscheidung: Nichtversetzung \u2013 ja oder nein?<\/a><\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;1563&#8243; img_size=&#8221;full&#8221; add_caption=&#8221;yes&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<a name=\"regelungen\"><\/a><\/p>\n<h2>Regelungen bei Nichtversetzung<\/h2>\n<p>[\/vc_column_text][vc_column_text]\u00dcblicherweise kann sich das Sitzenbleiben bereits im Zwischenzeugnis mit der Bemerkung ank\u00fcndigen, dass die Versetzung gef\u00e4hrdet ist. Zus\u00e4tzlich gibt es in Form des \u201eblauen Briefes\u201c etwa 4 Wochen vor Schuljahresende noch eine letzte Warnung. Hat sich die Leistung bis zum n\u00e4chsten Zeugnis dann tats\u00e4chlich nicht verbessert, gibt es in den meisten Bundesl\u00e4ndern die M\u00f6glichkeit der Nachpr\u00fcfung.<\/p>\n<p>Das Sitzenbleiben wird immer wieder hei\u00df diskutiert. Nicht nur unter Eltern, sondern auch in der Politik. Da Bildung in Deutschland L\u00e4ndersache ist, gelten je nach Bundesland verschiedene Regeln. Diese k\u00f6nnen zus\u00e4tzlich nach Klassenstufe oder Schulform variieren. Auch die M\u00f6glichkeit der Nachpr\u00fcfung besteht nicht in allen Bundesl\u00e4ndern. In Berlin beispielsweise wurde die Ehrenrunde in den Sekundarschulen abgeschafft. Hier k\u00f6nnen Schuljahre nur noch freiwillig wiederholt werden. In Schleswig-Holstein dagegen gibt es die Nichtversetzung nur noch nach der 6. oder nach der 9. Klasse. Wie genau dieses Thema in Ihrem Heimatbundesland zurzeit organisiert ist, finden Sie auf den <a href=\"https:\/\/www.bildungsserver.de\/Kultusministerien-580-de.html\">Webseiten der Kultusministerien<\/a>. Oder aber Sie erkundigen sich bei der Schulleitung oder der Elternvertretung Ihrer Schule.<\/p>\n<p>Im Prinzip ist es f\u00fcr jedes Schulkind m\u00f6glich, eine Klasse freiwillig zu wiederholen. In folgenden F\u00e4llen ergibt es Sinn, dass Ihr Kind eine Stufe wiederholt:<\/p>\n<ul>\n<li>l\u00e4ngere Abwesenheiten aufgrund von Krankheit oder Krankenhausaufenthalt<\/li>\n<li>unruhige Phasen zu Hause (zum Beispiel Scheidung, Krankheit, Todesfall)<\/li>\n<li>schlechte Noten in mehreren oder allen F\u00e4chern<\/li>\n<li>pers\u00f6nliche Probleme als Ursache der Lernschwierigkeiten<\/li>\n<li>Probleme im Klassenzusammenhalt oder beim Zusammenspiel mit der Lehrkraft<\/li>\n<\/ul>\n<p>Weniger sinnvoll ist es in diesen F\u00e4llen:<\/p>\n<ul>\n<li>einzelne schw\u00e4chere F\u00e4cher\/Noten, aber solides Gesamtbild<\/li>\n<li>Umgang mit anderen Sch\u00fclern und Sch\u00fclerinnen sehr zur\u00fcckhaltend oder \u00e4ngstlich<\/li>\n<li>dauerhafte Lernunlust (Der Wechsel der Stufe allein hilft hier nicht.)<\/li>\n<li>absehbar vor\u00fcbergehende Ursachen der schlechten Leistung<\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<a name=\"abschaffung\"><\/a><\/p>\n<h2>Die Abschaffung der Nichtversetzung<\/h2>\n<p>[\/vc_column_text][vc_column_text]Bei der Einf\u00fchrung des Schulsystems mit Jahrgangsklassen ist man davon ausgegangen, dass gleichaltrige Kinder auch ungef\u00e4hr den gleichen Entwicklungsstand haben. Das sollte zu etwa gleichen schulischen Leistungen f\u00fchren. Ist das nicht der Fall, wird das Kind quasi ein Entwicklungslevel zur\u00fcckgestuft. Heutzutage ist dieses Modell sehr umstritten. In einer Studie der Bertelsmann-Stiftung wurde die Nichtversetzung als unwirksam gekennzeichnet. Die nicht versetzten Lernenden weisen laut der empirischen Untersuchung keine dauerhaft bessere kognitive Lernleistung in der niedrigeren Klassenstufe auf. Und auch beim vorherigen Klassenverband, von dem man annahm, er werde durch die Schwachen geschw\u00e4cht, konnte keine Verbesserung durch das Aussortieren festgestellt werden. Auch PISA 2009 untermauert diese These. Die dort gut abschneidenden L\u00e4nder wie Finnland und Singapur haben eine Widerholungsquote von 2,8 bzw. 5,4 %. In Deutschland liegt diese Quote eher bei 21 % und auf die schlechten Ergebnisse im PISA-Test m\u00fcssen wir sicher nicht genauer eingehen.<\/p>\n<p>Ein komplettes Jahr zu wiederholen ist sehr zeitintensiv. F\u00fcr die Sch\u00fcler und Sch\u00fclerinnen verl\u00e4ngert sich die Schulzeit entsprechend, was bedeutet, dass sie erst ein Jahr sp\u00e4ter ihre Ausbildung beginnen und ins Arbeitsleben einsteigen k\u00f6nnen. In der heutigen Leistungsgesellschaft ist das f\u00fcr Nichtversetzungs-Gegner ein K.-o.-Kriterium. Mit intensiveren Lernf\u00f6rderungen lie\u00dfen sich die Lernschw\u00e4chen auch kurzfristig beheben. Die j\u00e4hrlich ca. 250.000 Sitzenbleibenden kosten den Steuerhaushalt etwa eine Milliarde Euro. Dieses Geld w\u00e4re in kurzfristigen Pr\u00e4ventivma\u00dfnahmen besser aufgehoben. In Nordrhein-Westfalen etwa gibt es mit der Nachricht der Versetzungsgef\u00e4hrdung bei den Zwischenzeugnissen individuelle Empfehlungen f\u00fcr Lernunterst\u00fctzung. Auch das motivationssteigernde Programm \u201eDuales Lernen\u201c zwischen Schulen und Betrieben oder Werkst\u00e4tten ist hier denkbar.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/2&#8243;][vc_column_text]F\u00fcr das Schulkind selbst kann das Sitzenbleiben ein Synonym f\u00fcr das eigene Versagen sein. Es sch\u00e4mt sich vor den Freunden und Freundinnen und der Erwartungsdruck der Eltern steigt. Die Nichtversetzung wird f\u00fcr das Kind zu einer psychischen Belastung, die sich nat\u00fcrlich auf die Lernmotivation auswirkt. In der neuen Klasse m\u00fcssen die Wiederholenden neuen Anschluss finden und sich in das bestehende Klassenkonstrukt integrieren. Je nach Charakter Ihres Kindes kann das eine gro\u00dfe Herausforderung sein. Viele Kinder empfinden diese Tatsache als Bestrafung.[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;1562&#8243; img_size=&#8221;full&#8221; add_caption=&#8221;yes&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<a name=\"chance\"><\/a><\/p>\n<h2>Sitzenbleiben als Chance<\/h2>\n<p>[\/vc_column_text][vc_column_text]Auf der anderen Seite kann eine Nichtversetzung aber auch als neue Chance angesehen werden. Wie in der Einleitung angedeutet haben auch erfolgreiche M\u00e4nner wie Albert Einstein, Thomas Mann und Winston Churchill eine Ehrenrunde gedreht \u2013 und trotzdem ist etwas aus ihnen geworden. Ein \u201eblauer Brief\u201c ist also keine Katastrophe.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/2&#8243;][vc_column_text]Einigen Schulkindern gibt eine Wiederholung einer Klassenstufe mehr Selbstsicherheit. Denn wenn sie die Grundlagen nicht verstanden haben, kann auch der neue Stoff der h\u00f6heren Klassenstufe nicht aufgenommen werden. Die Kinder schalten dann ab oder st\u00f6ren im Unterricht. Aber nach dem Sitzenbleiben nehmen die ersten besseren Noten in den Klassenarbeiten ihnen die Angst und st\u00e4rken die Motivation. Der Wissensdurst wird von Neuem entfacht.[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;1565&#8243; img_size=&#8221;full&#8221; add_caption=&#8221;yes&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]Statt ein Kind mit st\u00e4ndiger Nachhilfe durch die Schulzeit zu schleifen, kann die Nichtversetzung zur Entlastung werden. Die Nachmittage muss es nicht mehr stundenlang am Schreibtisch verbringen, sondern hat mehr Zeit f\u00fcr Hobbys und Freundschaften. Auch diese au\u00dferschulischen Aktivit\u00e4ten st\u00e4rken die Pers\u00f6nlichkeit Ihres Kindes.<\/p>\n<p>Wie bereits erw\u00e4hnt ist das freiwillige Wiederholen f\u00fcr diejenigen Kinder hilfreich, die beispielsweise wegen einer Krankheit einen gro\u00dfen Teil des Unterrichts verpasst haben. Auch wenn Ihre Familie im letzten Jahr eine schwere Zeit durchgemacht hat, sei es wegen eines Scheidungsprozesses oder eines Todesfalls, konnte Ihr Kind sich wahrscheinlich weniger auf den Schulstoff konzentrieren und die Noten sacken ab. Auch hier ist die Nichtversetzung eine geeignete Ma\u00dfnahme f\u00fcr einen Neustart und ein besseres Zeugnis.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<a name=\"entscheidung\"><\/a><\/p>\n<h2>Schwere Entscheidung: Nichtversetzung \u2013 ja oder nein?<\/h2>\n<p>[\/vc_column_text][vc_column_text]Egal ob Ihr Kind aufgrund des Schulrechts zum Sitzenbleiben gen\u00f6tigt ist oder Sie Ihr Kind freiwillig zur\u00fcckstufen m\u00f6chten: Die hier genannten Pros und Kontras der Nichtversetzung sollen Ihnen einen umfassenden \u00dcberblick geben. Welchen Weg Sie f\u00fcr Ihr Kind am besten w\u00e4hlen, l\u00e4sst sich nicht pauschal beantworten, sondern h\u00e4ngt von jedem Einzelfall ab. Wichtig ist, dass Sie Ihr Kind aufmerksam beobachten und bei einem Leistungsabfall fr\u00fchzeitig Ma\u00dfnahmen ergreifen. <a href=\"https:\/\/learnattack.de\/magazin\/was-tun-bei-schlechten-noten\/\">Hier haben wir Tipps f\u00fcr Sie<\/a>, wie Sie bei schlechten Noten reagieren sollten.[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column width=&#8221;1\/2&#8243;][vc_column_text]Die Ausgabe der Zeugnisse kann bei den einen Freude, bei anderen aber auch Sorgen und \u00c4ngste ausl\u00f6sen. N\u00e4mlich dann, wenn die schlechten Noten die Versetzung gef\u00e4hrden. Wie Sie auf dieses erste Warnsignal reagieren k\u00f6nnen, haben wir Ihnen bereits hier ans Herz gelegt. Aber was tun, wenn dann tats\u00e4chlich der \u201eblaue Brief\u201c ins Haus flattert [&hellip;]<\/p>\n","protected":false},"author":27,"featured_media":1564,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4],"tags":[80,78,79,81,82],"class_list":["post-1561","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-schul-und-familienalltag","tag-ehrenrunde","tag-nichtversetzung","tag-sitzenbleiben","tag-versetzung","tag-versetzungsgefaehrdet"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nichtversetzung \u2013 Katastrophe oder neue Chance? - Duden Learnattack Eltern-Magazin<\/title>\n<meta name=\"description\" content=\"Sitzen bleiben ist doch kein Beinbruch \u2013 oder doch? Wir beleuchten in diesem Artikel die Vor- und Nachteile der Nichtversetzung.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/learnattack.de\/magazin\/nichtversetzung-pro-kontra\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nichtversetzung \u2013 Katastrophe oder neue Chance? - Duden Learnattack Eltern-Magazin\" \/>\n<meta property=\"og:description\" content=\"Sitzen bleiben ist doch kein Beinbruch \u2013 oder doch? Wir beleuchten in diesem Artikel die Vor- und Nachteile der Nichtversetzung.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/learnattack.de\/magazin\/nichtversetzung-pro-kontra\/\" \/>\n<meta property=\"og:site_name\" content=\"Duden Learnattack Eltern-Magazin\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/learnattack\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-16T12:38:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-08-29T13:01:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/learnattack.de\/magazin\/wp-content\/uploads\/2019\/05\/Nichtversetzung-pro-Kontra.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2124\" \/>\n\t<meta property=\"og:image:height\" content=\"1411\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"heike.ruethrich@learnattack.de\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Learnattack\" \/>\n<meta name=\"twitter:site\" content=\"@Learnattack\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"heike.ruethrich@learnattack.de\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nichtversetzung \u2013 Katastrophe oder neue Chance? - Duden Learnattack Eltern-Magazin","description":"Sitzen bleiben ist doch kein Beinbruch \u2013 oder doch? Wir beleuchten in diesem Artikel die Vor- und Nachteile der Nichtversetzung.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/learnattack.de\/magazin\/nichtversetzung-pro-kontra\/","og_locale":"de_DE","og_type":"article","og_title":"Nichtversetzung \u2013 Katastrophe oder neue Chance? - Duden Learnattack Eltern-Magazin","og_description":"Sitzen bleiben ist doch kein Beinbruch \u2013 oder doch? Wir beleuchten in diesem Artikel die Vor- und Nachteile der Nichtversetzung.","og_url":"https:\/\/learnattack.de\/magazin\/nichtversetzung-pro-kontra\/","og_site_name":"Duden Learnattack Eltern-Magazin","article_publisher":"https:\/\/www.facebook.com\/learnattack","article_published_time":"2019-05-16T12:38:52+00:00","article_modified_time":"2019-08-29T13:01:19+00:00","og_image":[{"width":2124,"height":1411,"url":"https:\/\/learnattack.de\/magazin\/wp-content\/uploads\/2019\/05\/Nichtversetzung-pro-Kontra.jpg","type":"image\/jpeg"}],"author":"heike.ruethrich@learnattack.de","twitter_card":"summary_large_image","twitter_creator":"@Learnattack","twitter_site":"@Learnattack","twitter_misc":{"Verfasst von":"heike.ruethrich@learnattack.de","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/learnattack.de\/magazin\/nichtversetzung-pro-kontra\/#article","isPartOf":{"@id":"https:\/\/learnattack.de\/magazin\/nichtversetzung-pro-kontra\/"},"author":{"name":"heike.ruethrich@learnattack.de","@id":"https:\/\/learnattack.de\/magazin\/#\/schema\/person\/22c9d06c71eaade0c2d55cbc6510f648"},"headline":"Nichtversetzung \u2013 Katastrophe oder neue Chance?","datePublished":"2019-05-16T12:38:52+00:00","dateModified":"2019-08-29T13:01:19+00:00","mainEntityOfPage":{"@id":"https:\/\/learnattack.de\/magazin\/nichtversetzung-pro-kontra\/"},"wordCount":1319,"image":{"@id":"https:\/\/learnattack.de\/magazin\/nichtversetzung-pro-kontra\/#primaryimage"},"thumbnailUrl":"https:\/\/learnattack.de\/magazin\/wp-content\/uploads\/2019\/05\/Nichtversetzung-pro-Kontra.jpg","keywords":["Ehrenrunde","Nichtversetzung","Sitzenbleiben","Versetzung","versetzungsgef\u00e4hrdet"],"articleSection":["Schul- &amp; Familienalltag"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/learnattack.de\/magazin\/nichtversetzung-pro-kontra\/","url":"https:\/\/learnattack.de\/magazin\/nichtversetzung-pro-kontra\/","name":"Nichtversetzung \u2013 Katastrophe oder neue Chance? - Duden Learnattack Eltern-Magazin","isPartOf":{"@id":"https:\/\/learnattack.de\/magazin\/#website"},"primaryImageOfPage":{"@id":"https:\/\/learnattack.de\/magazin\/nichtversetzung-pro-kontra\/#primaryimage"},"image":{"@id":"https:\/\/learnattack.de\/magazin\/nichtversetzung-pro-kontra\/#primaryimage"},"thumbnailUrl":"https:\/\/learnattack.de\/magazin\/wp-content\/uploads\/2019\/05\/Nichtversetzung-pro-Kontra.jpg","datePublished":"2019-05-16T12:38:52+00:00","dateModified":"2019-08-29T13:01:19+00:00","author":{"@id":"https:\/\/learnattack.de\/magazin\/#\/schema\/person\/22c9d06c71eaade0c2d55cbc6510f648"},"description":"Sitzen bleiben ist doch kein Beinbruch \u2013 oder doch? Wir beleuchten in diesem Artikel die Vor- und Nachteile der Nichtversetzung.","breadcrumb":{"@id":"https:\/\/learnattack.de\/magazin\/nichtversetzung-pro-kontra\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/learnattack.de\/magazin\/nichtversetzung-pro-kontra\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/learnattack.de\/magazin\/nichtversetzung-pro-kontra\/#primaryimage","url":"https:\/\/learnattack.de\/magazin\/wp-content\/uploads\/2019\/05\/Nichtversetzung-pro-Kontra.jpg","contentUrl":"https:\/\/learnattack.de\/magazin\/wp-content\/uploads\/2019\/05\/Nichtversetzung-pro-Kontra.jpg","width":2124,"height":1411,"caption":"\u00a9Ridofranz"},{"@type":"BreadcrumbList","@id":"https:\/\/learnattack.de\/magazin\/nichtversetzung-pro-kontra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Eltern-Magazin","item":"https:\/\/learnattack.de\/magazin\/"},{"@type":"ListItem","position":2,"name":"Schul- &amp; Familienalltag","item":"https:\/\/learnattack.de\/magazin\/thema\/schul-und-familienalltag\/"},{"@type":"ListItem","position":3,"name":"Nichtversetzung \u2013 Katastrophe oder neue Chance?"}]},{"@type":"WebSite","@id":"https:\/\/learnattack.de\/magazin\/#website","url":"https:\/\/learnattack.de\/magazin\/","name":"Duden Learnattack Eltern-Magazin","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/learnattack.de\/magazin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/learnattack.de\/magazin\/#\/schema\/person\/22c9d06c71eaade0c2d55cbc6510f648","name":"heike.ruethrich@learnattack.de","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/5abdddebfc221aa08f701bb073ba554b85fde4260b568cf262234359d1495d17?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5abdddebfc221aa08f701bb073ba554b85fde4260b568cf262234359d1495d17?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5abdddebfc221aa08f701bb073ba554b85fde4260b568cf262234359d1495d17?s=96&d=mm&r=g","caption":"heike.ruethrich@learnattack.de"},"url":"https:\/\/learnattack.de\/magazin\/author\/heike-ruethrichlearnattack-de\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/learnattack.de\/magazin\/wp-json\/wp\/v2\/posts\/1561","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/learnattack.de\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/learnattack.de\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/learnattack.de\/magazin\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/learnattack.de\/magazin\/wp-json\/wp\/v2\/comments?post=1561"}],"version-history":[{"count":5,"href":"https:\/\/learnattack.de\/magazin\/wp-json\/wp\/v2\/posts\/1561\/revisions"}],"predecessor-version":[{"id":1570,"href":"https:\/\/learnattack.de\/magazin\/wp-json\/wp\/v2\/posts\/1561\/revisions\/1570"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/learnattack.de\/magazin\/wp-json\/wp\/v2\/media\/1564"}],"wp:attachment":[{"href":"https:\/\/learnattack.de\/magazin\/wp-json\/wp\/v2\/media?parent=1561"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/learnattack.de\/magazin\/wp-json\/wp\/v2\/categories?post=1561"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/learnattack.de\/magazin\/wp-json\/wp\/v2\/tags?post=1561"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}