{"id":1503,"date":"2015-12-26T09:57:22","date_gmt":"2015-12-26T08:57:22","guid":{"rendered":"https:\/\/learnattack.de\/journal\/?p=1503"},"modified":"2025-04-29T20:08:15","modified_gmt":"2025-04-29T18:08:15","slug":"plum-pudding-und-knallbonbons-weihnachten-in-grossbritannien","status":"publish","type":"post","link":"https:\/\/learnattack.de\/journal\/plum-pudding-und-knallbonbons-weihnachten-in-grossbritannien\/","title":{"rendered":"Plumpudding und Knallbonbons \u2013 Weihnachten in Gro\u00dfbritannien"},"content":{"rendered":"<p>Du glaubst, Weihnachten ist \u00fcberall gleich? Weit gefehlt! Weihnachten in Gro\u00dfbritannien hat andere Traditionen\u00a0und dort feiern sie das Fest der Liebe entsprechend anders als in Deutschland. Wir erkl\u00e4ren dir die Unterschiede!<\/p>\n<h2>Weihnachten in Gro\u00dfbritannien<\/h2>\n<h3>Christmas Eve<\/h3>\n<p>Weihnachten in Gro\u00dfbritannien ist der 24. Dezember, Heiligabend, weniger bedeutend als der erste (<em>Christmas Day<\/em>) und zweite Weihnachtsfeiertag (<em>Boxing Day<\/em>).<\/p>\n<p>An Heiligabend h\u00e4ngen die Kinder Socken an den Kamin, die der Legende nach der Weihnachtsmann \u00fcber Nacht bef\u00fcllt. Die Erz\u00e4hlung besagt, Santa Claus stelle zusammen mit seinen Elfen Spielzeuge in Gr\u00f6nland her und liefere sie am Weihnachtsabend aus.<\/p>\n<p>Seinen Schlitten ziehen neun Rentiere, von denen Rudolph mit der roten Nase das bekannteste ist. F\u00fcr sie\u00a0liegen in den Wohnzimmern zur St\u00e4rkung teilweise M\u00f6hren aus. Santa Claus bekommt Milch (oder Sherry) und s\u00fc\u00dfes Geb\u00e4ck.<\/p>\n<h3>Christmas Day<\/h3>\n<p>Am Morgen des ersten Weihnachtsfeiertages packen die Kinder die Geschenke aus. Anschlie\u00dfend fr\u00fchst\u00fcckt die Familie zusammen und geht in den Gottesdienst.<\/p>\n<p>Das gro\u00dfe Weihnachtsessen gibt es am Nachmittag. Gegen Abend h\u00e4lt die Queen ihre Weihnachtsrede im Fernsehen, die sich die meisten Briten ansehen. Da das britische K\u00f6nigshaus mittlerweile einen Kanal auf <a href=\"https:\/\/www.youtube.com\/user\/TheRoyalChannel\">Youtube<\/a> besitzt, k\u00f6nnen Interessierte die Rede international ein wenig zeitversetzt verfolgen.<\/p>\n<h3>Boxing Day<\/h3>\n<p>Der zweite Weihnachtsfeiertag ist traditionell der Tag, um Freunde und Angestellte zu beschenken. Die Sitte geht auf das Mittelalter zur\u00fcck. Damals leerten die Priester die Opferst\u00f6cke der Kirche und verteilten das Geld an die Bed\u00fcrftigen.<\/p>\n<p>Sp\u00e4ter entstand der Brauch, dass wohlhabende Menschen die \u00dcberbleibsel ihrer Feste sammelten und in Boxen packten, die sie an ihre Angestellten verteilten. Daher kommt der Name <em>Boxing Day<\/em> am zweiten Tag an Weihnachten in Gro\u00dfbritannien.<\/p>\n<h3>Christmas dinner<\/h3>\n<p>Das <a href=\"http:\/\/projectbritain.com\/Xmas\/dinner.html\">Weihnachtsessen<\/a> beginnt f\u00fcr die Briten am Morgen mit Garnelen und ger\u00e4uchertem Lachs. Am Nachmittag folgt der Hauptgang. Er besteht, \u00e4hnlich wie in Deutschland, aus Gans oder Truthahn. In fr\u00fcheren Zeiten servierten die Briten die Tiere in Haut und Federn eingewickelt.<\/p>\n<p>Nach dem Festessen folgt der Plumpudding. Der auch <em>figgy pudding<\/em> genannte Nachtisch ist weniger s\u00fc\u00df, enth\u00e4lt viel Trockenobst, N\u00fcsse, Gew\u00fcrze und Fett. Zus\u00e4tzlich tr\u00e4nken die Briten den Pudding in den meisten F\u00e4llen in Alkohol (zum Beispiel mit Brandy).<\/p>\n<p>Beim\u00a0Verzehr des Puddings werden\u00a0W\u00fcnsche\u00a0formuliert. Jeder Esser hat einen Wunsch frei. Im Pudding befindet sich traditionell eine M\u00fcnze, weshalb er\u00a0vorsichtig verspeist wird. Der Wunsch desjenigen, dessen Pudding das Geldst\u00fcck enth\u00e4lt (und der es hoffentlich nicht schluckt), geht in Erf\u00fcllung.<\/p>\n<h3>Christmas tree<\/h3>\n<p>Sich einen Tannenbaum in die Stube zu stellen ist in Gro\u00dfbritannien kein alter Brauch. Erst im 19. Jahrhundert kam der Weihnachtsbaum aus Deutschland auf die Insel. Prinz Albert, der Ehemann der britischen K\u00f6nigin Victoria, brachte die Tradition aus seinem Heimatland mit.<\/p>\n<h3>Mistletoe<\/h3>\n<p>Der Mistelzweig soll magische F\u00e4higkeiten besitzen. Viel bekannter ist die Tradition, sich unter dem Mistelzweig zu k\u00fcssen. Der Kuss steht nicht zwangsl\u00e4ufig f\u00fcr eine romantische Beziehung der beiden K\u00fcssenden. Er kann ebenso eine lange Freundschaft und Wohlwollen bedeuten.<\/p>\n<p>Zum\u00a0K\u00fcssen unter dem Mistelzweig geh\u00f6rt eine Besonderheit:\u00a0Nach jedem Kuss pfl\u00fccken die Protagonisten eine Beere des Zweigs. Sind keine Beeren mehr da, ist das K\u00fcssen beendet.<\/p>\n<h3>Christmas crackers<\/h3>\n<p>Christmas crackers sind bunte Knallbonbons, die kleine \u00dcberraschungen enthalten. Die Briten \u00f6ffnen die Bonbons, indem sie im Kreis sitzend jeweils mit der linken Hand an einem Bonbon ziehen. Mit der rechten Hand halten sie das\u00a0Bonbon des Sitznachbarn fest. Das Bonbon gibt eine kleine Papierkrone, ein kleines Geschenk und einen auf Papier geschriebenen Witz frei. Die kleinen Pr\u00e4sente sind Artikel wie Stifte, Notizbl\u00f6cke oder Taschenspiegel.<\/p>\n<p>Was h\u00e4ltst du von den britischen Traditionen? Welche h\u00e4ttest du gern in Deutschland?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Du glaubst, Weihnachten ist weltweit gleich? Weit gefehlt! In Gro\u00dfbritannien feiern sie das Fest der Liebe anders als in Deutschland. Wir erkl\u00e4ren dir die Unterschiede!<\/p>\n","protected":false},"author":30,"featured_media":5921,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[645],"class_list":["post-1503","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-freizeit-und-unterhaltung","tag-weihnachten"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Weihnachten in Gro\u00dfbritannien<\/title>\n<meta name=\"description\" content=\"Du glaubst, Weihnachten ist \u00fcberall gleich? Wir erkl\u00e4ren dir wie Weihnachten in Gro\u00dfbritannien gefeiert wird und warum das so ist.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/learnattack.de\/journal\/plum-pudding-und-knallbonbons-weihnachten-in-grossbritannien\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Weihnachten in Gro\u00dfbritannien\" \/>\n<meta property=\"og:description\" content=\"Du glaubst, Weihnachten ist \u00fcberall gleich? Wir erkl\u00e4ren dir wie Weihnachten in Gro\u00dfbritannien gefeiert wird und warum das so ist.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/learnattack.de\/journal\/plum-pudding-und-knallbonbons-weihnachten-in-grossbritannien\/\" \/>\n<meta property=\"og:site_name\" content=\"Duden Learnattack Sch\u00fcler-Journal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/learnattack\" \/>\n<meta property=\"article:published_time\" content=\"2015-12-26T08:57:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-29T18:08:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/learnattack.de\/journal\/wp-content\/uploads\/2015\/12\/weihnachten-in-gro\u00dfbritiannien.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2121\" \/>\n\t<meta property=\"og:image:height\" content=\"1414\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Theresa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Learnattack\" \/>\n<meta name=\"twitter:site\" content=\"@Learnattack\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Theresa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Weihnachten in Gro\u00dfbritannien","description":"Du glaubst, Weihnachten ist \u00fcberall gleich? Wir erkl\u00e4ren dir wie Weihnachten in Gro\u00dfbritannien gefeiert wird und warum das so ist.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/learnattack.de\/journal\/plum-pudding-und-knallbonbons-weihnachten-in-grossbritannien\/","og_locale":"de_DE","og_type":"article","og_title":"Weihnachten in Gro\u00dfbritannien","og_description":"Du glaubst, Weihnachten ist \u00fcberall gleich? Wir erkl\u00e4ren dir wie Weihnachten in Gro\u00dfbritannien gefeiert wird und warum das so ist.","og_url":"https:\/\/learnattack.de\/journal\/plum-pudding-und-knallbonbons-weihnachten-in-grossbritannien\/","og_site_name":"Duden Learnattack Sch\u00fcler-Journal","article_publisher":"https:\/\/www.facebook.com\/learnattack","article_published_time":"2015-12-26T08:57:22+00:00","article_modified_time":"2025-04-29T18:08:15+00:00","og_image":[{"width":2121,"height":1414,"url":"https:\/\/learnattack.de\/journal\/wp-content\/uploads\/2015\/12\/weihnachten-in-gro\u00dfbritiannien.jpg","type":"image\/jpeg"}],"author":"Theresa","twitter_card":"summary_large_image","twitter_creator":"@Learnattack","twitter_site":"@Learnattack","twitter_misc":{"Verfasst von":"Theresa","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/learnattack.de\/journal\/plum-pudding-und-knallbonbons-weihnachten-in-grossbritannien\/#article","isPartOf":{"@id":"https:\/\/learnattack.de\/journal\/plum-pudding-und-knallbonbons-weihnachten-in-grossbritannien\/"},"author":{"name":"Theresa","@id":"https:\/\/learnattack.de\/journal\/#\/schema\/person\/1c4bb2e6366867c1e34e72d2889776e1"},"headline":"Plumpudding und Knallbonbons \u2013 Weihnachten in Gro\u00dfbritannien","datePublished":"2015-12-26T08:57:22+00:00","dateModified":"2025-04-29T18:08:15+00:00","mainEntityOfPage":{"@id":"https:\/\/learnattack.de\/journal\/plum-pudding-und-knallbonbons-weihnachten-in-grossbritannien\/"},"wordCount":637,"image":{"@id":"https:\/\/learnattack.de\/journal\/plum-pudding-und-knallbonbons-weihnachten-in-grossbritannien\/#primaryimage"},"thumbnailUrl":"https:\/\/learnattack.de\/journal\/wp-content\/uploads\/2015\/12\/weihnachten-in-gro\u00dfbritiannien.jpg","keywords":["Weihnachten"],"articleSection":["Freizeit &amp; Unterhaltung"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/learnattack.de\/journal\/plum-pudding-und-knallbonbons-weihnachten-in-grossbritannien\/","url":"https:\/\/learnattack.de\/journal\/plum-pudding-und-knallbonbons-weihnachten-in-grossbritannien\/","name":"Weihnachten in Gro\u00dfbritannien","isPartOf":{"@id":"https:\/\/learnattack.de\/journal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/learnattack.de\/journal\/plum-pudding-und-knallbonbons-weihnachten-in-grossbritannien\/#primaryimage"},"image":{"@id":"https:\/\/learnattack.de\/journal\/plum-pudding-und-knallbonbons-weihnachten-in-grossbritannien\/#primaryimage"},"thumbnailUrl":"https:\/\/learnattack.de\/journal\/wp-content\/uploads\/2015\/12\/weihnachten-in-gro\u00dfbritiannien.jpg","datePublished":"2015-12-26T08:57:22+00:00","dateModified":"2025-04-29T18:08:15+00:00","author":{"@id":"https:\/\/learnattack.de\/journal\/#\/schema\/person\/1c4bb2e6366867c1e34e72d2889776e1"},"description":"Du glaubst, Weihnachten ist \u00fcberall gleich? Wir erkl\u00e4ren dir wie Weihnachten in Gro\u00dfbritannien gefeiert wird und warum das so ist.","breadcrumb":{"@id":"https:\/\/learnattack.de\/journal\/plum-pudding-und-knallbonbons-weihnachten-in-grossbritannien\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/learnattack.de\/journal\/plum-pudding-und-knallbonbons-weihnachten-in-grossbritannien\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/learnattack.de\/journal\/plum-pudding-und-knallbonbons-weihnachten-in-grossbritannien\/#primaryimage","url":"https:\/\/learnattack.de\/journal\/wp-content\/uploads\/2015\/12\/weihnachten-in-gro\u00dfbritiannien.jpg","contentUrl":"https:\/\/learnattack.de\/journal\/wp-content\/uploads\/2015\/12\/weihnachten-in-gro\u00dfbritiannien.jpg","width":2121,"height":1414,"caption":"iStock.com\/dglimages"},{"@type":"BreadcrumbList","@id":"https:\/\/learnattack.de\/journal\/plum-pudding-und-knallbonbons-weihnachten-in-grossbritannien\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Sch\u00fcler-Journal","item":"https:\/\/learnattack.de\/journal\/"},{"@type":"ListItem","position":2,"name":"Freizeit &amp; Unterhaltung","item":"https:\/\/learnattack.de\/journal\/thema\/freizeit-und-unterhaltung\/"},{"@type":"ListItem","position":3,"name":"Plumpudding und Knallbonbons \u2013 Weihnachten in Gro\u00dfbritannien"}]},{"@type":"WebSite","@id":"https:\/\/learnattack.de\/journal\/#website","url":"https:\/\/learnattack.de\/journal\/","name":"Duden Learnattack Sch\u00fcler-Journal","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/learnattack.de\/journal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/learnattack.de\/journal\/#\/schema\/person\/1c4bb2e6366867c1e34e72d2889776e1","name":"Theresa","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/learnattack.de\/journal\/wp-content\/uploads\/2017\/10\/theresa-150x150.jpg","url":"https:\/\/learnattack.de\/journal\/wp-content\/uploads\/2017\/10\/theresa-150x150.jpg","contentUrl":"https:\/\/learnattack.de\/journal\/wp-content\/uploads\/2017\/10\/theresa-150x150.jpg","caption":"Theresa"},"description":"Hi, ich bin Theresa und schreibe f\u00fcr die Sch\u00fclerzeitung der Sekundarstufe 2 am Gymnasium. Mit Duden Learnattack arbeite ich gerne zusammen, da ich interessante Einblicke in das Thema Online Journalismus bekomme. Nach meinem Abi m\u00f6chte ich dies hauptberuflich machen. Schreibt mir gern oder hinterlasst ein Kommentar, ich antworte gern :) LG Theresa","url":"https:\/\/learnattack.de\/journal\/author\/theresa-hoefer\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/learnattack.de\/journal\/wp-json\/wp\/v2\/posts\/1503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/learnattack.de\/journal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/learnattack.de\/journal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/learnattack.de\/journal\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/learnattack.de\/journal\/wp-json\/wp\/v2\/comments?post=1503"}],"version-history":[{"count":14,"href":"https:\/\/learnattack.de\/journal\/wp-json\/wp\/v2\/posts\/1503\/revisions"}],"predecessor-version":[{"id":4120,"href":"https:\/\/learnattack.de\/journal\/wp-json\/wp\/v2\/posts\/1503\/revisions\/4120"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/learnattack.de\/journal\/wp-json\/wp\/v2\/media\/5921"}],"wp:attachment":[{"href":"https:\/\/learnattack.de\/journal\/wp-json\/wp\/v2\/media?parent=1503"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/learnattack.de\/journal\/wp-json\/wp\/v2\/categories?post=1503"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/learnattack.de\/journal\/wp-json\/wp\/v2\/tags?post=1503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}